


{"id":18,"date":"2011-07-21T07:17:33","date_gmt":"2011-07-21T07:17:33","guid":{"rendered":"http:\/\/team.inria.fr\/template1\/?page_id=18"},"modified":"2013-06-11T19:24:11","modified_gmt":"2013-06-11T17:24:11","slug":"research","status":"publish","type":"page","link":"https:\/\/www-secreizh.irisa.fr\/fr\/research\/","title":{"rendered":"Recherche"},"content":{"rendered":"<p><\/p>\n<li>\n<h2>Axe de recherche 1<\/h2>\n<p>&#8230;&#8230;.<\/p>\n<li>\n<h2>Axe de recherche 2<\/h2>\n<p>&#8230;&#8230;&#8230;.<\/p>\n<li>\n<h2>Axe de recherche 3<\/h2>\n<p>&#8230;&#8230;&#8230;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Axe de recherche 1 &#8230;&#8230;. Axe de recherche 2 &#8230;&#8230;&#8230;. Axe de recherche 3 &#8230;&#8230;&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-18","page","type-page","status-publish","hentry","nodate","item-wrap"],"_links":{"self":[{"href":"https:\/\/www-secreizh.irisa.fr\/fr\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www-secreizh.irisa.fr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www-secreizh.irisa.fr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www-secreizh.irisa.fr\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www-secreizh.irisa.fr\/fr\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":6,"href":"https:\/\/www-secreizh.irisa.fr\/fr\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":327,"href":"https:\/\/www-secreizh.irisa.fr\/fr\/wp-json\/wp\/v2\/pages\/18\/revisions\/327"}],"wp:attachment":[{"href":"https:\/\/www-secreizh.irisa.fr\/fr\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}